{"id":6761249,"date":"2026-03-03T15:49:28","date_gmt":"2026-03-03T14:49:28","guid":{"rendered":"https:\/\/clone-ind.com\/?post_type=product&#038;p=6761249"},"modified":"2026-09-02T13:51:15","modified_gmt":"2026-09-02T11:51:15","slug":"unidirektionale-verbundflachsfasern-300-g-m%c2%b2-breite-35-cm","status":"publish","type":"product","link":"https:\/\/clone-ind.com\/de\/shop\/fibres-de-lin-composite-unidirectionnel-300-g-m%c2%b2-largeur-35-cm\/","title":{"rendered":"UD-Verbundflachsfasern 300 g\/m\u00b2 \u2013 Breite 35 cm"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>ARTIKEL WIRD PRO LINEARMETER VERKAUFT<\/strong><\/p>\n<h3>Unidirektionales Leinengewebe (UD) \u2013 300 g\/m\u00b2 \u2013 AMPLITEX\u2122<\/h3>\n<p>Verbundverst\u00e4rkung aus nat\u00fcrlichen Flachsfasern <strong>ampliTex\u2122<\/strong>, unidirektionale Architektur (0\u00b0), vorgesehen f\u00fcr Anwendungen, die eine mechanische Verst\u00e4rkung in einer Hauptachse mit hoher D\u00e4mpfungskapazit\u00e4t erfordern.<\/p>\n<hr \/>\n<h3>PRODUKTBESCHREIBUNG<\/h3>\n<p>Unidirektionales Gewebe aus Flachsfasern, die in eine einzige Richtung (0\u00b0) ausgerichtet sind und durch einen leichten Bindefaden zusammengehalten werden.<br \/>\nDiese Verst\u00e4rkung wurde f\u00fcr technische Verbundwerkstoffe entwickelt und bietet eine leistungsstarke Alternative zu Glasfaser mit verbessertem Schwingungsverhalten.<\/p>\n<hr \/>\n<h3>TECHNISCHE DATEN<\/h3>\n<ul>\n<li>Faser: Leinen (ampliTex\u2122)<\/li>\n<li>Ausrichtung: Unidirektional (0\u00b0)<\/li>\n<li>Gewicht: 300 g\/m\u00b2<\/li>\n<li>Breite: 350 mm<\/li>\n<li>Verpackung: Laufmeter<\/li>\n<\/ul>\n<hr \/>\n<h3>MECHANISCHE EIGENSCHAFTEN<\/h3>\n<p><strong>Zusammengesetzte Werte (Richtwerte)<\/strong><\/p>\n<ul>\n<li>Zugfestigkeit: ~383 MPa<\/li>\n<li>Zugmodul: ~32 GPa<\/li>\n<\/ul>\n<p><strong>Ballaststoffe (Richtwerte)<\/strong><\/p>\n<ul>\n<li>Zugfestigkeit: ~700 MPa<\/li>\n<li>Zugmodul: ~58,5 GPa<\/li>\n<li>Dichte: 1,35 g\/cm\u00b3<\/li>\n<\/ul>\n<hr \/>\n<h3>EIGENSCHAFTEN<\/h3>\n<ul>\n<li>Gute mechanische Verst\u00e4rkung entlang der Faserachse<\/li>\n<li>Hervorragende Vibrationsd\u00e4mpfung<\/li>\n<li>Spezifische Steifigkeit gr\u00f6\u00dfer als Glasfaser<\/li>\n<li>Niedrige Dichte \u2192 Leichtbaustrukturen<\/li>\n<li>Sehr gute Kompatibilit\u00e4t mit Kohlenstoff (Hybridisierung)<\/li>\n<li>Reduzierter \u00f6kologischer Fu\u00dfabdruck<\/li>\n<\/ul>\n<hr \/>\n<h3>DURCHF\u00dcHRUNG<\/h3>\n<p>Kompatible Prozesse:<\/p>\n<ul>\n<li>Kontaktschichtung<\/li>\n<li>Vakuuminfusion<\/li>\n<li>Vakuum-\/Pressformung<\/li>\n<\/ul>\n<p>Kompatible Harze:<\/p>\n<ul>\n<li>Epoxidharz<\/li>\n<li>Polyester<\/li>\n<\/ul>\n<p><strong>Empfehlungen:<\/strong><\/p>\n<ul>\n<li>Vortrocknen empfohlen: 110 \u00b0C \/ 15 min<\/li>\n<li>Richtwert f\u00fcr die Harzdosierung (UD 300 g\/m\u00b2): ~390 g\/m\u00b2<\/li>\n<li>Vorsicht bei der Impr\u00e4gnierung: hohe Absorptionskapazit\u00e4t<\/li>\n<\/ul>\n<hr \/>\n<h3>ANWENDUNGEN<\/h3>\n<ul>\n<li>Snowboards \/ Skier (l\u00e4ngsgerichtete sto\u00dfd\u00e4mpfende Verst\u00e4rkung)<\/li>\n<li>Sandwichstrukturen<\/li>\n<li>Technische Verbundteile<\/li>\n<li>Sport, Bootfahren, Mobilit\u00e4t<\/li>\n<\/ul>\n<hr \/>\n<h3>VERKAUFSBEDINGUNGEN<\/h3>\n<ul>\n<li>Breite: 350 mm<\/li>\n<li>Wird pro laufendem Meter verkauft<\/li>\n<li>F\u00fcr ein Paar Skier werden etwa 4 Meter ben\u00f6tigt.<\/li>\n<\/ul>\n<hr \/>\n<h3>BEOBACHTUNGEN<\/h3>\n<ul>\n<li>Trockenprodukt (nicht vorimpr\u00e4gniert)<\/li>\n<li>Die Faserrichtung ist bei der Implementierung zu beachten.<\/li>\n<li>Quellung des Flachses w\u00e4hrend der Impr\u00e4gnierung (normales Verhalten)<\/li>\n<li>Das Endergebnis h\u00e4ngt vom Herstellungsverfahren und dem verwendeten Harz ab.<\/li>\n<\/ul>\n<hr \/>\n<h2>TECHNISCHE HINWEISE \u2013 POSITIONIERUNG VON LIN UD<\/h2>\n<p>UD-Flachs wird verwendet, um Folgendes teilweise oder vollst\u00e4ndig zu ersetzen:<\/p>\n<ul>\n<li>UD-Carbon (zu steif\/trocken)<\/li>\n<li>Glasfaser (weniger effizient unter dynamischen Bedingungen)<\/li>\n<\/ul>\n<h3>Typische Verwendung<\/h3>\n<ul>\n<li>Zus\u00e4tzlich zu Kohlenstoff \u2192 verbesserter Komfort<\/li>\n<li>In L\u00e4ngsschichten \u2192 progressivere Flexibilit\u00e4t<\/li>\n<li>Hybridstruktur \u2192 bester Kompromiss zwischen Leistung und Fahrgef\u00fchl<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>&nbsp; ARTICLE VENDU AU M\u00c8TRE LIN\u00c9AIRE TISSU LIN UNIDIRECTIONNEL (UD) \u2013 300 g\/m\u00b2 \u2013 AMPLITEX\u2122 Renfort composite en fibres naturelles de lin ampliTex\u2122, architecture unidirectionnelle (0\u00b0), destin\u00e9 aux applications n\u00e9cessitant un renfort m\u00e9canique dans un axe principal avec un fort pouvoir d\u2019amortissement. DESCRIPTION PRODUIT Tissu unidirectionnel compos\u00e9 de fibres de lin align\u00e9es dans une seule [&hellip;]<\/p>\n","protected":false},"featured_media":6761401,"template":"","meta":[],"product_brand":[],"product_cat":[533],"product_tag":[],"class_list":["post-6761249","product","type-product","status-publish","has-post-thumbnail","product_cat-tissus-fibres","tm-no-options","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"group_of_quantity":0,"min_quantity":1,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","gallery_images":[6761402,6761403],"_links":{"self":[{"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product\/6761249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/media\/6761401"}],"wp:attachment":[{"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/media?parent=6761249"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product_brand?post=6761249"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product_cat?post=6761249"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product_tag?post=6761249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}