{"id":1429,"date":"2015-10-12T15:32:43","date_gmt":"2015-10-12T13:32:43","guid":{"rendered":"http:\/\/www.clone-ind.com\/?post_type=product&#038;p=1429"},"modified":"2026-09-02T13:48:16","modified_gmt":"2026-09-02T11:48:16","slug":"ultraleichter-und-leistungsstarker-balsa-leinen-kern-ski","status":"publish","type":"product","link":"https:\/\/clone-ind.com\/de\/shop\/noyau-balsa-lin-ultra-leger-et-performant-skis\/","title":{"rendered":"Ultraleichter und leistungsstarker Balsa-Lin-Kern zur Herstellung Ihrer Ski"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Dieser Hochleistungskern aus Balsaholz und Flachs ist unglaublich leicht: nur 0,18 g\/cm\u00b3. Federleicht! Er ist der leichteste auf dem Markt! Dank der Flachsfaserverst\u00e4rkung, der steifsten aller Naturfasern, bietet er bemerkenswerte Eigenschaften. Ihre Beine werden die Lebendigkeit und Reaktionsf\u00e4higkeit dieses ultraleichten Naturkerns von Bcomp lieben!<\/p>\n<ul>\n<li>Abmessungen in mm: 1900 x 147 x 15<\/li>\n<li>extrem leicht mit einer Dichte von 180 kg\/m3<\/li>\n<li>gleiche Scherfestigkeit wie Holzkerne<\/li>\n<li>hohe Best\u00e4ndigkeit gegen Druck und St\u00f6\u00dfe<\/li>\n<li>Hoher Widerstand gegen Schichtabl\u00f6sung<\/li>\n<li>hervorragende D\u00e4mpfungseigenschaften<\/li>\n<li>Balsa <a href=\"https:\/\/ic.fsc.org\/index.htm\" target=\"_blank\" rel=\"noopener noreferrer\">FSC-zertifiziert<\/a> und europ\u00e4ischer Leinenverbundstoff<\/li>\n<\/ul>\n<p><em>Erh\u00e4ltlich in weiteren Gr\u00f6\u00dfen f\u00fcr Splitboards und Snowboards.<\/em><\/p>\n<p><strong>Preis inklusive 1 Kern zur Herstellung eines Paares Ski<\/strong><\/p>","protected":false},"featured_media":1439,"template":"","meta":[],"product_brand":[],"product_cat":[535],"product_tag":[],"class_list":["post-1429","product","type-product","status-publish","has-post-thumbnail","product_cat-noyaux","tm-no-options","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","gallery_images":[1731,6825],"_links":{"self":[{"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product\/1429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/media\/1439"}],"wp:attachment":[{"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/media?parent=1429"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product_brand?post=1429"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product_cat?post=1429"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/clone-ind.com\/de\/wp-json\/wp\/v2\/product_tag?post=1429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}